{"id":1220,"date":"2019-06-11T21:14:10","date_gmt":"2019-06-11T19:14:10","guid":{"rendered":"https:\/\/groom.su4.modevmedia.com\/?page_id=1220"},"modified":"2019-09-30T23:59:19","modified_gmt":"2019-09-30T21:59:19","slug":"avis-legaux","status":"publish","type":"page","link":"https:\/\/groom.su4.modevmedia.com\/fr\/avis-legaux\/","title":{"rendered":"Avis l\u00e9gaux"},"content":{"rendered":"<h2>Conditions g\u00e9n\u00e9rales d\u2019utilisation<\/h2>\n<p>Les conditions g\u00e9n\u00e9rales d\u2019utilisation \u00e9nonc\u00e9es ci-dessous expliquent comment vous pouvez utiliser le pr\u00e9sent site Web (le \u00ab site \u00bb). Toute mention du \u00ab site \u00bb, dans ces conditions g\u00e9n\u00e9rales d\u2019utilisation, inclut les sites Web suivants (et toutes les pages Web qui y sont associ\u00e9es) : stg-groomprod-staging.kinsta.cloud. Ce site, et notamment le logiciel (le \u00ab logiciel \u00bb) que nous utilisons pour jumeler les candidats et les employeurs potentiels (le \u00ab service \u00bb), est exploit\u00e9 par son propri\u00e9taire, Groom &amp; Associ\u00e9s Int\u00e9rim inc. (\u00ab Groom &amp; Associ\u00e9s Canada \u00bb). Les mots \u00ab nous \u00bb, \u00ab nos \u00bb et \u00ab notre \u00bb, dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales, font r\u00e9f\u00e9rence \u00e0 Groom &amp; Associ\u00e9s Canada et incluent aussi, le cas \u00e9ch\u00e9ant, nos soci\u00e9t\u00e9s affili\u00e9es, nos fournisseurs de services, nos fournisseurs et nos sous-traitants. Nos bureaux sont situ\u00e9s \u00e0 l\u2019adresse suivante :<\/p>\n<p>360 Rue St Jacques,<br \/>\nMontr\u00e9al, Qu\u00e9bec<br \/>\nH2Y 1P6<\/p>\n<p><strong>VEUILLEZ LIRE ATTENTIVEMENT CES CONDITIONS G\u00c9N\u00c9RALES D\u2019UTILISATION AVANT D\u2019UTILISER LE SITE.<\/strong><\/p>\n<h3>Acceptation<\/h3>\n<p>En consultant ou en utilisant ce site ou en indiquant autrement votre consentement, vous acceptez d\u2019\u00eatre li\u00e9 par les pr\u00e9sentes conditions g\u00e9n\u00e9rales et les documents auxquels elles font r\u00e9f\u00e9rence et d\u00e9clarez que, au mieux de votre connaissance, l\u2019information que vous fournissez \u00e0 l\u2019entreprise, \u00e0 ses repr\u00e9sentants et \u00e0 ses agents est compl\u00e8te et exacte. Une fausse d\u00e9claration peut entra\u00eener votre exclusion de tout placement ou une cessation d\u2019emploi ult\u00e9rieure pour cause juste et suffisante si vous \u00eates plac\u00e9 par l\u2019entreprise. Les mots \u00ab vous \u00bb, \u00ab votre \u00bb et \u00ab vos \u00bb utilis\u00e9s dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales font r\u00e9f\u00e9rence \u00e0 tous les particuliers et \u00e0 toutes les entit\u00e9s qui consultent ou utilisent le site pour quelque raison que ce soit. Si vous \u00eates en d\u00e9saccord avec n\u2019importe laquelle des conditions \u00e9nonc\u00e9es dans les pr\u00e9sentes ou n\u2019acceptez pas de les respecter, vous devez cesser d\u2019utiliser le site imm\u00e9diatement. Pour toute question concernant le site, veuillez communiquer avec notre service \u00e0 la client\u00e8le au : &#x69;&#x6e;&#x66;&#111;&#64;&#103;ro&#x6f;&#x6d;&#x61;&#x73;&#115;&#111;ci&#x65;&#x73;&#x2e;&#x63;&#111;&#109;.<\/p>\n<h3>Modifications<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada peut, en tout temps et \u00e0 sa discr\u00e9tion exclusive, r\u00e9viser les pr\u00e9sentes conditions g\u00e9n\u00e9rales d\u2019utilisation, sans avis pr\u00e9alable ni obligation envers vous ni aucune autre personne, en mettant \u00e0 jour la pr\u00e9sente publication. Puisque vous \u00eates li\u00e9 par ces conditions g\u00e9n\u00e9rales, il vous est conseill\u00e9 de consulter cette page p\u00e9riodiquement pour v\u00e9rifier si des modifications ou des mises \u00e0 jour y ont \u00e9t\u00e9 apport\u00e9es.<\/p>\n<h3>Admissibilit\u00e9<\/h3>\n<p>Le site est con\u00e7u \u00e0 l\u2019intention des r\u00e9sidents du Canada qui ont atteint l\u2019\u00e2ge de la majorit\u00e9 dans leur province ou territoire de r\u00e9sidence et qui peuvent passer un contrat ayant force obligatoire sous le r\u00e9gime du droit applicable.<\/p>\n<h3>Accessibilit\u00e9<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada s\u2019engage \u00e0 offrir des services accessibles aux personnes handicap\u00e9es et \u00e0 fournir un environnement s\u00e9curitaire, accueillant et respectueux pour tous. Nous visons \u00e0 r\u00e9pondre rapidement aux besoins des personnes handicap\u00e9es. Nous y arriverons en supprimant les obstacles \u00e0 l\u2019accessibilit\u00e9, en pr\u00e9venant la cr\u00e9ation de tels obstacles et en respectant les exigences l\u00e9gales applicables. Si vous \u00e9prouvez des probl\u00e8mes pour acc\u00e9der au site ou \u00e0 toute information qui y est contenue, veuillez communiquer avec nous \u00e0 <a href=\"mailto:info&#64;groomassocie&#115;&#46;&#99;&#111;&#109;\">&#x69;&#110;f&#x6f;&#64;&#103;&#x72;&#x6f;&#111;m&#x61;&#115;s&#x6f;&#x63;&#105;e&#x73;&#46;c&#x6f;&#x6d;<\/a>.<\/p>\n<h3>Politique de confidentialit\u00e9<\/h3>\n<p>En utilisant le site ou le service, il se peut que vous mettiez \u00e0 la disposition de Groom &amp; Associ\u00e9s Canada certains renseignements vous concernant. Groom &amp; Associ\u00e9s Canada collecte, utilise et divulgue de l\u2019information sur votre utilisation du site et vos renseignements personnels en conformit\u00e9 avec notre politique de confidentialit\u00e9 (accessible \u00e0 l\u2019adresse suivante : <a href=\"https:\/\/groom.su4.modevmedia.com\/fr\/avis-legaux\/#politique-de-confidentialite\">https:\/\/groom.su4.modevmedia.com\/fr\/avis-legaux\/#politique-de-confidentialite<\/a>), dont les conditions g\u00e9n\u00e9rales sont incluses aux pr\u00e9sentes par renvoi. Nous utiliserons les renseignements que vous fournissez (y compris, notamment, les donn\u00e9es personnelles d\u00e9licates) pour faciliter le processus de recrutement et les fonctions administratives qui s\u2019y rattachent. Dans ce but, il nous faut, entre autres choses, traiter et stocker des renseignements (notamment des donn\u00e9es personnelles d\u00e9licates) ainsi que les transmettre ou les rendre accessibles en ligne \u00e0 des employeurs et clients potentiels; des renseignements sur des postes vacants et des placements sont transmis aux candidats et peuvent \u00eatre publi\u00e9s directement sur le site. Dans le cadre du processus de recrutement, nous avons recours \u00e0 des tiers qui nous aident \u00e0 traiter vos renseignements. Nous pouvons recueillir et agr\u00e9ger des donn\u00e9es \u00e0 partir des renseignements que vous nous fournissez pour mieux conna\u00eetre l\u2019ensemble de nos utilisateurs et vous offrir un meilleur service. Nous pouvons aussi communiquer des renseignements agr\u00e9g\u00e9s \u00e0 des tiers choisis, sans divulguer de nom ni de renseignements permettant l\u2019identification de particuliers. Vous consentez \u00e0 ce que nous utilisions les renseignements que vous nous fournissez (y compris les donn\u00e9es personnelles d\u00e9licates) de toutes ces fa\u00e7ons. Nous traitons conform\u00e9ment \u00e0 la l\u00e9gislation relative \u00e0 la protection des donn\u00e9es toutes les donn\u00e9es que vous nous fournissez en remplissant les formulaires d\u2019inscription ou de candidature en ligne ainsi que tout autre formulaire, \u00e9valuation ou renseignement personnel que vous remplissez ou fournissez en utilisant ce site. En acceptant ces conditions g\u00e9n\u00e9rales et chaque fois que vous utilisez le site ou le service, vous consentez \u00e0 la collecte, \u00e0 l\u2019utilisation et \u00e0 la divulgation par Groom &amp; Associ\u00e9s Canada de vos renseignements personnels conform\u00e9ment \u00e0 notre politique de confidentialit\u00e9, y compris \u00e0 toutes ses mises \u00e0 jour, sans avis pr\u00e9alable ni obligation envers vous ni aucune autre personne.<\/p>\n<h3>T\u00e9moins<\/h3>\n<p>Lorsque vous visitez le site ou le service, nous pouvons recueillir certains renseignements par des moyens automatiques, notamment des t\u00e9moins. Notre politique en mati\u00e8re de t\u00e9moins, qui d\u00e9crit l\u2019information sur les t\u00e9moins utilis\u00e9s sur notre site, s\u2019applique aussi \u00e0 votre utilisation du site.<\/p>\n<h3>Avis concernant la propri\u00e9t\u00e9 intellectuelle<\/h3>\n<p>Droit d\u2019auteur \u00a9 2019 Groom &amp; Associ\u00e9s Canada. Tous droits r\u00e9serv\u00e9s. \u00ab Contenu \u00bb s\u2019entend de tout contenu HTML, texte, image, vid\u00e9o, contenu audio ou autre contenu multim\u00e9dia, ainsi que de tout logiciel, renseignement ou document auquel il vous est donn\u00e9 acc\u00e8s sur le site, qui est soumis au site, qui subsiste sur le site ou qui y est accessible. Nous sommes propri\u00e9taires ou titulaires de licence de tous les droits de propri\u00e9t\u00e9 intellectuelle sur notre site et dans les documents qui y sont publi\u00e9s. Notamment, GROOM &amp; ASSOCI\u00c9S, GOOD TO KNOW YOU et SHAPING THE WORLD OF WORK sont des marques de commerce de Groom &amp; Associ\u00e9s Holding N.V., utilis\u00e9es sous licence. EMPLOI SUR MESURE, SUPERVISEUR SUR MESURE, ENTREPRISE SUR MESURE sont des marques de commerce de Groom &amp; Associ\u00e9s Canada. Les noms de tous les autres produits et services mentionn\u00e9s sur le site sont des marques de commerce de leurs propri\u00e9taires respectifs. Les \u0153uvres sur ce site sont prot\u00e9g\u00e9es par les lois et les trait\u00e9s sur le droit d\u2019auteur partout dans le monde. Vous pouvez imprimer une copie et t\u00e9l\u00e9charger des extraits de pages de notre site pour votre usage personnel. Vous pouvez aussi attirer l\u2019attention d\u2019autres personnes de votre organisation sur le contenu publi\u00e9 sur notre site. Vous ne devez pas modifier les copies sur papier ou num\u00e9riques de tout document imprim\u00e9 ou t\u00e9l\u00e9charg\u00e9 de quelque fa\u00e7on que ce soit et vous ne devez utiliser ni illustrations, ni photos, ni s\u00e9quences vid\u00e9o ou audio ni images s\u00e9par\u00e9ment de tout texte qui les accompagne. Vous acceptez de ne pas modifier, contourner ni supprimer aucun avis de propri\u00e9t\u00e9 intellectuelle contenu dans le site. Groom &amp; Associ\u00e9s Canada et tous ses collaborateurs identifi\u00e9s, le cas \u00e9ch\u00e9ant, doivent toujours \u00eatre nomm\u00e9s \u00e0 titre d\u2019auteurs du contenu de notre site. Vous ne devez utiliser aucune partie du contenu de notre site \u00e0 des fins commerciales sans avoir obtenu une licence \u00e0 cet effet de notre part ou de nos cessionnaires de licence. Si vous imprimez, copiez ou t\u00e9l\u00e9chargez toute partie de notre site en violation de ces conditions g\u00e9n\u00e9rales, votre droit d\u2019utiliser le site prendra fin imm\u00e9diatement et vous devrez, \u00e0 notre choix, renvoyer ou d\u00e9truire toute copie que vous aurez faite des documents. Aucun \u00e9nonc\u00e9 contenu dans ce site ne peut \u00eatre interpr\u00e9t\u00e9 comme octroyant, implicitement ou autrement, une licence ou un droit d\u2019utilisation de toute propri\u00e9t\u00e9 intellectuelle sans notre permission \u00e9crite pr\u00e9alable.<\/p>\n<h3>Renseignements soumis par vous et communications avec le site<\/h3>\n<p>Vous ne pouvez utiliser ce site qu\u2019\u00e0 des fins l\u00e9gitimes pour chercher un emploi ou faire progresser votre carri\u00e8re. Vous ne devez, en aucune circonstance, chercher \u00e0 compromettre la s\u00e9curit\u00e9 du site ou de tout renseignement qui y est soumis ou rendu accessible. Notamment, vous ne devez chercher ni \u00e0 consulter, ni \u00e0 modifier ou supprimer un renseignement auquel vous n\u2019avez pas l\u2019autorisation d\u2019acc\u00e9der, ni \u00e0 surcharger le syst\u00e8me par pollupostage ou inondation, ni \u00e0 agir ou utiliser un appareil, une routine ou un logiciel pour faire tomber en panne, ralentir, endommager ou perturber autrement le fonctionnement du site, ni tenter de d\u00e9chiffrer, de d\u00e9sassembler ou de modifier les logiciels, l\u2019information ou les codes inclus dans le site. Vous \u00eates seul responsable de tout renseignement que vous soumettez au site, ainsi que de la v\u00e9rification de leur v\u00e9racit\u00e9, de leur exactitude et de leur actualit\u00e9. Il vous incombe aussi enti\u00e8rement de veiller \u00e0 ce que ces renseignements ne soient ni trompeurs, ni susceptibles d\u2019\u00eatre trompeurs ou d\u2019induire en erreur, de v\u00e9rifier qu\u2019ils sont exempts de tout caract\u00e8re discriminatoire, obsc\u00e8ne, offensant ou diffamatoire et qu\u2019ils ne sont pas autrement ill\u00e9gaux, ill\u00e9gitimes ou en violation des lois, r\u00e8glements, lignes directrices ou codes de pratique applicables, ni des droits d\u2019auteur, des marques de commerce ou d\u2019autres droits de propri\u00e9t\u00e9 intellectuelle de toute personne dans toute province et tout territoire. Vous \u00eates aussi responsable de veiller \u00e0 ce que tous les renseignements, donn\u00e9es et fichiers soient exempts de virus ou d\u2019autres routines ou moteurs qui pourraient endommager ou perturber tout syst\u00e8me ou toute donn\u00e9e, avant de les soumettre au site. Nous nous r\u00e9servons le droit de supprimer du site toute information soumise par vous, \u00e0 notre discr\u00e9tion exclusive, en tout temps et pour quelque raison que ce soit, sans devoir donner d\u2019explication.<\/p>\n<h3>Exactitude des renseignements<\/h3>\n<p>Bien que nous fassions tous les efforts possibles pour veiller \u00e0 l\u2019exactitude et \u00e0 l\u2019exhaustivit\u00e9 de l\u2019information contenue sur le site, il nous est impossible de le faire \u00e0 l\u2019\u00e9gard de certains renseignements, qui nous sont fournis par des tiers. Nous d\u00e9clinons toute responsabilit\u00e9 d\u00e9coulant de toute inexactitude ou omission dans quelque renseignement que ce soit dans le site, ainsi que toute responsabilit\u00e9 en ce qui a trait aux renseignements sur le site qui sont fournis par vous, par un autre utilisateur du site ou par toute autre personne.<\/p>\n<h3>Aucun conseil juridique<\/h3>\n<p>Le contenu de ce site est fourni uniquement pour votre information g\u00e9n\u00e9rale et dans le but de vous renseigner \u00e0 notre sujet et sur nos produits, nouvelles, caract\u00e9ristiques et services ainsi que sur autres sites Web susceptibles de pr\u00e9senter un int\u00e9r\u00eat. Il ne constitue pas un conseil technique, financier ou juridique ni aucun autre type de conseil ou d\u2019avis, et ne doit pas servir de fondement \u00e0 quelque fin que ce soit. Vous devez obtenir des conseils et des recommandations d\u2019un professionnel qualifi\u00e9 avant de prendre ou de vous engager \u00e0 prendre des mesures qui s\u2019appuieraient sur une information fournie dans le site ou par son interm\u00e9diaire.<\/p>\n<h3>Disponibilit\u00e9 du site<\/h3>\n<p>Bien que nous d\u00e9ployions des efforts raisonnables sur le plan commercial pour veiller \u00e0 la disponibilit\u00e9 du site, nous ne d\u00e9clarons ni ne garantissons d\u2019aucune fa\u00e7on qu\u2019il sera accessible de fa\u00e7on continue en tout temps pour un usage ininterrompu de votre part. Groom &amp; Associ\u00e9s Canada se r\u00e9serve le droit de suspendre ou de modifier le service qui vous est offert sur le site, le site lui-m\u00eame ou une partie du site, en tout temps et \u00e0 la discr\u00e9tion exclusive de Groom &amp; Associ\u00e9s Canada, avec ou sans avis pr\u00e9alable \u00e0 votre intention.<\/p>\n<h3>Limitation de responsabilit\u00e9<\/h3>\n<p>Rien, dans les pr\u00e9sentes conditions d\u2019utilisation, n\u2019exclut ni ne limite notre responsabilit\u00e9 en cas de d\u00e9c\u00e8s ou de l\u00e9sion corporelle d\u00e9coulant d\u2019une n\u00e9gligence, d\u2019une fraude ou d\u2019une assertion frauduleuse et inexacte de notre part, ni toute autre responsabilit\u00e9 qui ne peut \u00eatre exclue ni limit\u00e9e par le droit applicable.<br \/>\nDans la mesure permise par la loi, nous excluons toute garantie, assertion ou autre condition, explicite ou implicite, qui pourrait s\u2019appliquer \u00e0 notre site ou \u00e0 son contenu. Nous ne sommes en aucun cas responsables, envers l\u2019utilisateur, de pertes ou de dommages, m\u00eame pr\u00e9visibles, que ce soit en mati\u00e8re contractuelle ou d\u00e9lictuelle (y compris la n\u00e9gligence), de violation d\u2019une obligation d\u2019origine l\u00e9gislative ou autre, d\u00e9coulant de ce qui suit ou ayant trait \u00e0 ce qui suit, selon le cas :<\/p>\n<ul>\n<li>l\u2019utilisation du site ou l\u2019incapacit\u00e9 de l\u2019utiliser;<\/li>\n<li>l\u2019utilisation de tout contenu publi\u00e9 sur notre site ou le fait de se fonder sur ce contenu.<\/li>\n<\/ul>\n<p>Si vous \u00eates un utilisateur professionnel, veuillez noter que nous ne sommes pas responsables, en particulier, de ce qui suit :<\/p>\n<ul>\n<li>pertes de profits, de ventes, d\u2019affaires ou de revenu;<\/li>\n<li>interruption des activit\u00e9s;<\/li>\n<li>perte d\u2019\u00e9conomies pr\u00e9vues;<\/li>\n<li>perte d\u2019occasions d\u2019affaires, de survaleur ou de r\u00e9putation;<\/li>\n<li>toute perte ou tout dommage indirect ou cons\u00e9quent.<\/li>\n<\/ul>\n<p>Nous ne sommes en aucun cas responsables de toute perte ou de tout dommage caus\u00e9s par un virus, une attaque par d\u00e9ni de service distribu\u00e9 ou un autre contenu technologiquement nuisible qui pourrait infecter votre mat\u00e9riel informatique, vos programmes informatiques, vos donn\u00e9es ou tout autre contenu exclusif en raison de votre utilisation de notre site ou du t\u00e9l\u00e9chargement de contenu de notre site ou de tout site Web qui y est mis en lien. Nous n\u2019endossons aucune responsabilit\u00e9 quant au contenu de sites Web mis en lien sur notre site. La pr\u00e9sence de ces liens ne doit pas \u00eatre interpr\u00e9t\u00e9e comme une approbation de notre part des sites Web concern\u00e9s. Nous ne sommes pas responsables des pertes ou dommages pouvant d\u00e9couler de votre utilisation de ces sites Web. Certains des biens ou des services offerts par l\u2019interm\u00e9diaire de ce site pourraient \u00eatre illicites ou par ailleurs interdits dans certains pays hors du Canada. Si vous tentez de commander, de recevoir ou d\u2019acheter de tels produits ou services ou d\u2019en profiter autrement, nous n\u2019assumons aucune responsabilit\u00e9 relativement \u00e0 toute perte subie par vous, dans le cadre de l\u2019utilisation de ce site, que vous n\u2019auriez pas subie en y acc\u00e9dant comme r\u00e9sident canadien (y compris si nous sommes emp\u00each\u00e9s de traiter toute candidature ou demande d\u2019information en vertu de toute loi, de tout r\u00e8glement ou de toute r\u00e8gle applicable dans quelque pays que ce soit).<\/p>\n<h3>Indemnisation<\/h3>\n<p>Vous acceptez d\u2019indemniser et de d\u00e9fendre Groom &amp; Associ\u00e9s Canada, ses soci\u00e9t\u00e9s affili\u00e9es, ses fournisseurs de services, ses fournisseurs et ses sous-traitants, ainsi que leurs mandataires, administrateurs, cadres, employ\u00e9s, fournisseurs d\u2019information, fournisseurs de services, fournisseurs, sous-traitants, conc\u00e9dants de licence et titulaires de licences (collectivement appel\u00e9s les \u00ab parties indemnis\u00e9es \u00bb), et de les exon\u00e9rer de toute responsabilit\u00e9 \u00e0 l\u2019\u00e9gard des r\u00e9clamations, d\u00e9penses et co\u00fbts, notamment des honoraires d\u2019avocats et des frais de justice raisonnables, engag\u00e9s par les parties indemnis\u00e9es relativement \u00e0 toute r\u00e9clamation ou demande qui d\u00e9coule de votre utilisation du site ou de votre violation des pr\u00e9sentes conditions, ou qui y est li\u00e9e; de plus, vous acceptez de pr\u00eater assistance et de collaborer dans toute la mesure raisonnable requise par les parties indemnis\u00e9es pour leur d\u00e9fense contre de telles r\u00e9clamations ou demandes.<\/p>\n<h3>Hyperliens et sites Web de tiers<\/h3>\n<p>Ce site propose des liens automatiques vers d\u2019autres sites Web qui pourraient vous int\u00e9resser. Nous n\u2019assumons aucune responsabilit\u00e9 ni obligation \u00e0 l\u2019\u00e9gard du contenu de ces sites Web, dont les propri\u00e9taires peuvent n\u2019avoir aucune relation, commerciale ou autre, avec nous. L\u2019utilisation de liens automatiques pour acc\u00e9der \u00e0 ces sites Web est enti\u00e8rement \u00e0 vos risques.<\/p>\n<h3>Fin de l\u2019offre de service<\/h3>\n<p>Nous nous r\u00e9servons le droit, \u00e0 notre enti\u00e8re discr\u00e9tion, de mettre fin \u00e0 tout service offert sur le site et d\u2019en supprimer tout contenu. Nous pouvons aussi mettre fin \u00e0 votre acc\u00e8s au site, au service ou \u00e0 une partie du site ou du service en tout temps, avec ou sans motif ou avis, pour quelque raison que ce soit. Si vous souhaitez fermer votre compte, vous pouvez seulement cesser d\u2019utiliser le site; nous ne serons responsables ni de tenir \u00e0 jour ni de retourner les renseignements ou les documents que vous nous aurez fournis.<\/p>\n<h3>Comp\u00e9tence exclusive<\/h3>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d\u2019utilisation, ainsi que toute question aff\u00e9rente \u00e0 votre utilisation directe ou indirecte du site, sont r\u00e9gies par les lois de la Province de Qu\u00e9becet les lois f\u00e9d\u00e9rales applicables dans la province de Qu\u00e9bec. Tout litige devra \u00eatre r\u00e9gl\u00e9 devant les tribunaux situ\u00e9s dans le district de Montr\u00e9al, en la province de Qu\u00e9bec. N\u00e9anmoins, ce qui pr\u00e9c\u00e8de ne limite pas la capacit\u00e9 de Groom &amp; Associ\u00e9s Canada de s\u2019adresser aux tribunaux d\u2019une autre juridiction afin de demander les recours injonctifs et redressements n\u00e9cessaires pour mettre fin \u00e0 une ou des violations, par vous, de la pr\u00e9sente entente.<\/p>\n<div id=\"politique-de-confidentialite\">&nbsp;<\/div>\n<h2>Politique en mati\u00e8re de confidentialit\u00e9<\/h2>\n<p>Groom &amp; Associ\u00e9s Interim Inc (\u00ab Groom &amp; Associ\u00e9s Canada \u00bb) s\u2019engage \u00e0 prendre toutes les mesures raisonnables pour pr\u00e9server la confidentialit\u00e9 de tous les renseignements personnels qu\u2019elle recueille, conform\u00e9ment aux lois applicables.<br \/>\nBut : La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab Politique \u00bb) a pour but d\u2019\u00e9noncer la fa\u00e7on dont Groom &amp; Associ\u00e9s Canada recueille, utilise, communique et g\u00e8re par ailleurs les renseignements personnels des demandeurs d\u2019emploi, des candidats et des visiteurs de notre site Web, accessible \u00e0 l\u2019adresse suivante : stg-groomprod-staging.kinsta.cloud (le \u00ab Site Web \u00bb). Cette Politique ne s\u2019applique pas aux employ\u00e9s internes, aux travailleurs temporaires, aux ressources assign\u00e9es, aux stagiaires en alternance travail-\u00e9tudes, stagiaires, aux b\u00e9n\u00e9voles et aux travailleurs autonomes de Groom &amp; Associ\u00e9s Canada.<\/p>\n<p>Propri\u00e9taire : Responsable de la protection des renseignements personnels<br \/>\nP\u00e9riode d\u2019\u00e9valuation : Au moins tous les deux ans ou plus t\u00f4t en cas de r\u00e9forme l\u00e9gislative ou selon ce qui est n\u00e9cessaire pour assurer le respect de la confidentialit\u00e9 des donn\u00e9es.<\/p>\n<p>Renseignements personnels : \u00ab Renseignements personnels \u00bb s\u2019entend de renseignements concernant une personne identifiable. Les renseignements personnels d\u2019une personne comprennent son nom, son adresse personnelle, son curriculum vitae, ses r\u00e9f\u00e9rences, ses \u00e9tudes et ses ant\u00e9c\u00e9dents de travail ainsi que d\u2019autres renseignements li\u00e9s \u00e0 l\u2019emploi. Toutefois, ils excluent les coordonn\u00e9es professionnelles lorsqu\u2019elles sont utilis\u00e9es pour communiquer avec une personne dans le cadre de ses fonctions professionnelles, comme les coordonn\u00e9es figurant sur une carte de visite.<\/p>\n<h3>Collecte et utilisation des renseignements personnels<\/h3>\n<p>La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab Politique \u00bb) a pour but d\u2019\u00e9noncer la fa\u00e7on dont Groom &amp; Associ\u00e9s Canada recueille, utilise, communique et g\u00e8re par ailleurs les renseignements personnels des demandeurs d\u2019emploi, des candidats et des visiteurs de notre site Web, accessible \u00e0 l\u2019adresse suivante : stg-groomprod-staging.kinsta.cloud (le \u00ab Site Web \u00bb). Cette Politique ne s\u2019applique pas aux employ\u00e9s internes, aux travailleurs temporaires, aux ressources assign\u00e9es, aux stagiaires en alternance travail-\u00e9tudes, stagiaires, aux b\u00e9n\u00e9voles et aux travailleurs autonomes de Groom &amp; Associ\u00e9s Canada.<\/p>\n<p>Propri\u00e9taire : Responsable de la protection des renseignements personnels<br \/>\nP\u00e9riode d\u2019\u00e9valuation : Au moins tous les deux ans ou plus t\u00f4t en cas de r\u00e9forme l\u00e9gislative ou selon ce qui est n\u00e9cessaire pour assurer le respect de la confidentialit\u00e9 des donn\u00e9es.<\/p>\n<p>Renseignements personnels : \u00ab Renseignements personnels \u00bb s\u2019entend de renseignements concernant une personne identifiable. Les renseignements personnels d\u2019une personne comprennent son nom, son adresse personnelle, son curriculum vitae, ses r\u00e9f\u00e9rences, ses \u00e9tudes et ses ant\u00e9c\u00e9dents de travail ainsi que d\u2019autres renseignements li\u00e9s \u00e0 l\u2019emploi. Toutefois, ils excluent les coordonn\u00e9es professionnelles lorsqu\u2019elles sont utilis\u00e9es pour communiquer avec une personne dans le cadre de ses fonctions professionnelles, comme les coordonn\u00e9es figurant sur une carte de visite.<\/p>\n<p>Dans le cadre de ses activit\u00e9s commerciales, Groom &amp; Associ\u00e9s Canada recueille, utilise et communique habituellement des Renseignements personnels pour faciliter la recherche, la s\u00e9lection et le recrutement de candidats. Groom &amp; Associ\u00e9s Canada peut utiliser des services en ligne pour rechercher et recruter des candidats, et, \u00e0 cette fin, peut divulguer des renseignements qui identifient ses candidats et ses employ\u00e9s aupr\u00e8s de ces fournisseurs de services.<\/p>\n<p>Plus pr\u00e9cis\u00e9ment, nous pouvons recueillir des renseignements personnels lorsqu\u2019une personne :<\/p>\n<ul>\n<li>visite notre Site Web;<\/li>\n<li>postule pour un emploi;<\/li>\n<li>s\u2019inscrit pour recevoir des alertes emploi;<\/li>\n<li>s\u2019inscrit pour recevoir des courriels relatifs \u00e0 l\u2019emploi et \u00e0 la carri\u00e8re;<\/li>\n<li>participe \u00e0 un sondage;<\/li>\n<li>partage une offre d\u2019emploi avec un ami;<\/li>\n<li>communique avec nous pour nous faire part d\u2019un commentaire, d\u2019une question ou d\u2019une plainte.<\/li>\n<\/ul>\n<h3>Visiter notre site web<\/h3>\n<p>Veuillez consulter notre Politique sur les t\u00e9moins et la publicit\u00e9 cibl\u00e9e par centre d\u2019int\u00e9r\u00eat pour obtenir de plus amples renseignements sur la fa\u00e7on dont nous utilisons les t\u00e9moins et les autres technologies de suivi sur notre Site Web et nos applications.<\/p>\n<h3>Poser sa candidature pour un emploi<\/h3>\n<p>Vous n\u2019avez pas besoin de vous inscrire ou de cr\u00e9er un compte pour visiter et parcourir certaines fonctions du Site Web. Toutefois, pour postuler un emploi, vous devez cr\u00e9er un compte. Nous recueillons vos nom et pr\u00e9nom, adresse \u00e9lectronique, num\u00e9ro de t\u00e9l\u00e9phone et mot de passe que vous choisissez afin de cr\u00e9er votre compte, et nous communiquons avec vous au sujet de votre demande d\u2019emploi ou d\u2019autres emplois qui pourraient vous int\u00e9resser. Lorsque vous postulez pour un emploi, nous recueillons \u00e9galement votre curriculum vitae que vous t\u00e9l\u00e9chargez ainsi que d\u2019autres documents li\u00e9s \u00e0 l\u2019emploi que vous nous fournissez, y compris les lettres de recommandation, relev\u00e9s de notes, r\u00e9compenses, etc. Nous utilisons ces renseignements pour traiter votre candidature, \u00e9valuer vos qualifications et votre aptitude \u00e0 l\u2019emploi pour lequel vous avez postul\u00e9 ainsi que pour d\u2019autres possibilit\u00e9s de carri\u00e8re actuelles et futures. Lorsque vous cr\u00e9ez votre profil Mon Groom &amp; Associ\u00e9s, nous pouvons \u00e9galement recueillir votre adresse r\u00e9sidentielle. Ce n\u2019est pas obligatoire toutefois.<\/p>\n<h3>Cr\u00e9ation d\u2019une alerte emploi<\/h3>\n<p>Si vous vous inscrivez pour recevoir des alertes d\u2019emploi, nous recueillerons votre adresse \u00e9lectronique, votre code postal et vos mots cl\u00e9s pour votre recherche d\u2019emploi. Nous utilisons ces informations afin de vous envoyer des courriels sur les nouveaux emplois dans votre r\u00e9gion qui correspondent \u00e0 vos champs d\u2019int\u00e9r\u00eat.<\/p>\n<h3>S\u2019inscrire aux communications<\/h3>\n<p>Nous pourrions vous offrir la possibilit\u00e9 de vous inscrire pour recevoir des courriels contenant des renseignements sur votre emploi et votre carri\u00e8re ou d\u2019autres bulletins d\u2019information de notre part. Lorsque vous vous inscrivez, nous recueillons des renseignements tels que votre nom et votre adresse \u00e9lectronique que nous utilisons pour vous envoyer les communications que vous avez accept\u00e9 de recevoir. Vous pouvez refuser de recevoir ces communications de notre part en suivant les directives de d\u00e9sabonnement fournies dans votre courriel, ou en communiquant avec nous aux coordonn\u00e9es ci-apr\u00e8s. Veuillez noter que vous pourriez continuer \u00e0 recevoir des alertes d\u2019emploi auxquelles vous vous \u00eates inscrit ainsi que des courriels concernant les emplois auxquels vous avez postul\u00e9.<\/p>\n<h3>Sondages<\/h3>\n<p>De temps \u00e0 autre, nous pouvons vous offrir la possibilit\u00e9 de participer \u00e0 l\u2019un de nos sondages. Les renseignements obtenus par le biais de nos sondages sont utilis\u00e9s dans une forme regroup\u00e9e qui ne permet pas de vous identifier personnellement. Nous utilisons ces renseignements pour nous aider \u00e0 mieux comprendre nos candidats et \u00e0 am\u00e9liorer notre site Web et nos services.<\/p>\n<h3>Service \u00e0 la client\u00e8le<\/h3>\n<p>Lorsque vous communiquez avec nous pour nous faire part d\u2019un commentaire, d\u2019une question ou d\u2019une plainte, il se peut qu\u2019on vous demande des renseignements permettant de vous identifier (comme votre nom, votre adresse \u00e9lectronique, votre adresse et un num\u00e9ro de t\u00e9l\u00e9phone) ainsi que des renseignements suppl\u00e9mentaires dont nous avons besoin pour r\u00e9pondre rapidement \u00e0 votre question ou \u00e0 votre commentaire ou \u00e0 votre plainte. Nous pouvons \u00e9galement conserver ces renseignements pour vous aider dans l\u2019avenir et pour am\u00e9liorer notre service \u00e0 la client\u00e8le, nos offres de produits et services, nos \u00e9v\u00e9nements et nos promotions.<\/p>\n<h3>Partage et communication de renseignements personnels<\/h3>\n<p>Nous ne communiquons pas, n\u2019\u00e9changeons pas, ne louons pas, ne vendons pas ou ne transf\u00e9rons pas par ailleurs vos renseignements personnels, sans votre consentement, sauf tel qu\u2019\u00e9nonc\u00e9 aux pr\u00e9sentes ou requis par la loi.<br \/>\nEmployeurs potentiels : Lorsque vous postulez pour un emploi, certaines informations peuvent \u00eatre mises \u00e0 la disposition de l\u2019entreprise aupr\u00e8s de laquelle vous avez postul\u00e9.<\/p>\n<h3>Fournisseurs de services<\/h3>\n<p>Nous pouvons transf\u00e9rer (ou rendre disponibles) vos renseignements personnels \u00e0 des entreprises membres du m\u00eame groupe que Groom &amp; Associ\u00e9s Canada ou \u00e0 des tiers qui fournissent des services pour notre compte. Par exemple, nous pouvons avoir recours \u00e0 des fournisseurs de services pour envoyer nos courriels, h\u00e9berger notre site Web et exploiter certaines de ses fonctions. Vos renseignements personnels peuvent \u00eatre conserv\u00e9s et trait\u00e9s par des entreprises membres du m\u00eame groupe que nous et des tiers fournisseurs de services en Europe et aux \u00c9tats-Unis. Nos fournisseurs de services re\u00e7oivent les renseignements dont ils ont besoin pour s\u2019acquitter de leurs fonctions d\u00e9sign\u00e9es et nous ne les autorisons pas \u00e0 utiliser ou \u00e0 communiquer des renseignements personnels \u00e0 leurs propres fins de commercialisation ou autres.<\/p>\n<h3>Op\u00e9rations commerciales<\/h3>\n<p>Nous pouvons transf\u00e9rer tout renseignement que nous d\u00e9tenons \u00e0 votre sujet \u00e0 titre d\u2019actif dans le cadre d\u2019une fusion ou d\u2019une vente propos\u00e9e ou r\u00e9alis\u00e9e (y compris les cessions effectu\u00e9es dans le cadre de proc\u00e9dures d\u2019insolvabilit\u00e9 ou de faillite) visant une partie ou la totalit\u00e9 de Groom &amp; Associ\u00e9s Canada ou dans le cadre d\u2019une restructuration d\u2019entreprise ou de tout autre changement de contr\u00f4le.<\/p>\n<h3>Exigences juridiques<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada, les entreprises membres du m\u00eame groupe qu\u2019elle aux \u00c9tats-Unis et \u00e0 l\u2019\u00e9tranger ainsi que les agences d\u2019administration ou de traitement de donn\u00e9es tierces peuvent communiquer \u00e0 d\u2019autres organisations vos renseignements personnels en r\u00e9ponse \u00e0 un mandat de perquisition ou \u00e0 toute autre enqu\u00eate ou ordonnance l\u00e9galement valide (ce qui peut inclure l\u2019acc\u00e8s l\u00e9gal par les autorit\u00e9s gouvernementales, les tribunaux ou les organismes d\u2019application de la loi canadiens, am\u00e9ricains ou \u00e9trangers), et ce, dans le cadre d\u2019une enqu\u00eate portant sur une rupture de contrat ou sur la violation d\u2019une loi, ou aux fins de d\u00e9tection, r\u00e9pression ou pr\u00e9vention de la fraude ou selon ce qui est par ailleurs requis ou autoris\u00e9 par les lois applicables canadiennes ou am\u00e9ricaines ou autres. <br \/>\nNous pouvons \u00e9galement communiquer des renseignements personnels lorsque cela est n\u00e9cessaire \u00e0 l\u2019\u00e9tablissement ou \u00e0 l\u2019exercice de r\u00e9clamations juridiques ou pour y opposer une d\u00e9fense, pour d\u00e9tecter, r\u00e9primer ou pr\u00e9venir la fraude, et pour enqu\u00eater sur des pertes ou pr\u00e9judices r\u00e9els ou pr\u00e9sum\u00e9s caus\u00e9s \u00e0 des personnes ou des biens ou pour les pr\u00e9venir.<\/p>\n<h3>Conservation de donn\u00e9es<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada tient des calendriers de conservation des dossiers pour s\u2019assurer que les Renseignements personnels ne sont conserv\u00e9s qu\u2019aussi longtemps que raisonnablement n\u00e9cessaire pour la r\u00e9alisation des fins pour lesquelles ils ont \u00e9t\u00e9 recueillis ou pour r\u00e9pondre \u00e0 d\u2019autres exigences juridiques ou commerciales valables.<\/p>\n<h3>Exactitude<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada prend des mesures raisonnables pour s\u2019assurer que les Renseignements personnels sont conserv\u00e9s d\u2019une mani\u00e8re aussi exacte que n\u00e9cessaire \u00e0 ses fins. Les demandes de correction de Renseignements personnels sont trait\u00e9es conform\u00e9ment aux droits accord\u00e9s en vertu des lois applicables et aux bonnes pratiques de tenue de dossiers.<\/p>\n<h3>Garanties : politique sur la s\u00e9curit\u00e9 des donn\u00e9es et la communication \u00e9lectronique<\/h3>\n<p>Groom &amp; Associ\u00e9s Canada prend des mesures de s\u00e9curit\u00e9 raisonnables pour prot\u00e9ger les Renseignements personnels contre l\u2019acc\u00e8s, la communication, la copie, l\u2019utilisation ou la modification ill\u00e9gaux ou non autoris\u00e9s. Ces mesures portent \u00e9galement sur la protection des renseignements contre la perte, le vol et les dommages. En particulier, Groom &amp; Associ\u00e9s Canada se dote de politiques, de proc\u00e9dures et de technologies pour pr\u00e9server la s\u00e9curit\u00e9 des Renseignements personnels d\u00e8s la collecte jusqu\u2019au moment de leur destruction.<\/p>\n<h3>Acc\u00e8s aux renseignements personnels et correction<\/h3>\n<p>Vous avez le droit d\u2019acc\u00e9der \u00e0 vos Renseignements personnels dont nous avons la garde et le contr\u00f4le, de les mettre \u00e0 jour et d\u2019en corriger les inexactitudes, sous r\u00e9serve de certaines exceptions pr\u00e9vues par la loi dans un d\u00e9lai de 30 jours. Vous pouvez acc\u00e9der \u00e0 certains Renseignements personnels en vous connectant \u00e0 votre compte sur le site Web <a href=\"https:\/\/clients.njoyn.com\/cl\/xweb\/Xweb.asp?tbtoken=Z1FQRlUSQBhzFHZ1RCBJFFZLBHldfVVeb11SUyoRfBUrLUsYL0sfdBYEPApcUR1TSD5l&amp;chk=dFlbQBJf&amp;page=NotLoggedIn&amp;CLID=95811#top\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/clients.njoyn.com\/cl\/xweb\/Xweb.asp?tbtoken=Z1FQRlUSQBhzFHZ1RCBJFFZLBHldfVVeb11SUyoRfBUrLUsYL0sfdBYEPApcUR1TSD5l&amp;chk=dFlbQBJf&amp;page=NotLoggedIn&amp;CLID=95811#top<\/a>. Autrement, toutes les demandes d\u2019acc\u00e8s aux Renseignements personnels ou de mise \u00e0 jour ou de correction de ceux-ci doivent \u00eatre faites par \u00e9crit et adress\u00e9es au Responsable de la protection de la vie priv\u00e9e de Groom &amp; Associ\u00e9s Canada \u00e0 l\u2019adresse suivante : <a href=\"&#109;&#97;&#x69;l&#116;&#x6f;&#x3a;i&#110;&#x66;&#x6f;&#64;&#103;&#x72;o&#111;&#x6d;&#x61;s&#115;&#x6f;&#x63;i&#101;&#x73;&#46;&#99;&#x6f;&#x6d;\">i&#110;&#102;&#x6f;&#x40;&#x67;&#x72;o&#111;&#109;&#97;&#x73;&#x73;&#x6f;ci&#101;&#115;&#x2e;&#x63;&#x6f;m<\/a>. Nous pouvons demander certains Renseignements personnels afin de v\u00e9rifier l\u2019identit\u00e9 de la personne qui demande l\u2019acc\u00e8s \u00e0 ses Renseignements personnels.<\/p>\n<h3>Recours disponibles<\/h3>\n<p>Toute plainte, question ou pr\u00e9occupation concernant la pr\u00e9sente Politique de confidentialit\u00e9 ou la fa\u00e7on dont Groom &amp; Associ\u00e9s Canada ou ses fournisseurs de services traitent vos Renseignements personnels doit \u00eatre adress\u00e9e au Responsable de protection de la vie priv\u00e9e local \u00e0 l\u2019adresse suivante : &#x69;&#x6e;&#x66;&#x6f;&#x40;&#x67;&#x72;&#x6f;&#x6f;&#x6d;&#x61;&#x73;&#x73;&#x6f;&#x63;&#x69;&#x65;&#x73;&#x2e;&#x63;&#x6f;&#x6d; et seront trait\u00e9es rapidement et en temps opportun. Si votre probl\u00e8me n\u2019a pas \u00e9t\u00e9 r\u00e9solu \u00e0 votre satisfaction, veuillez consulter la section Responsabilisation ci-dessus de la pr\u00e9sente politique.<\/p>\n<h3>Modifications \u00e0 la politique de confidentialit\u00e9<\/h3>\n<p>Cette Politique de confidentialit\u00e9 peut \u00eatre mise \u00e0 jour p\u00e9riodiquement afin de tenir compte de changements apport\u00e9s \u00e0 nos pratiques en mati\u00e8re de Renseignements personnels. La Politique de confidentialit\u00e9 r\u00e9vis\u00e9e sera affich\u00e9e sur le Site Web. Nous vous encourageons fortement \u00e0 consulter souvent cette Politique de confidentialit\u00e9 pour obtenir les renseignements les plus r\u00e9cents sur nos pratiques en mati\u00e8re de renseignements personnels.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conditions g\u00e9n\u00e9rales d\u2019utilisation Les conditions g\u00e9n\u00e9rales d\u2019utilisation \u00e9nonc\u00e9es ci-dessous expliquent comment vous pouvez utiliser le pr\u00e9sent site Web (le \u00ab site \u00bb). Toute mention du \u00ab site \u00bb, dans ces conditions g\u00e9n\u00e9rales d\u2019utilisation, inclut les sites Web suivants (et toutes les pages Web qui y sont associ\u00e9es) : stg-groomprod-staging.kinsta.cloud. Ce site, et notamment le logiciel [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":90,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1220","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/pages\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":6,"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/pages\/1220\/revisions"}],"predecessor-version":[{"id":2406,"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/pages\/1220\/revisions\/2406"}],"wp:attachment":[{"href":"https:\/\/groom.su4.modevmedia.com\/fr\/wp-json\/wp\/v2\/media?parent=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}